{"id":2075,"date":"2023-05-02T13:36:06","date_gmt":"2023-05-02T11:36:06","guid":{"rendered":"https:\/\/multisite.mindd.dev\/hap-maastricht\/?post_type=faq&#038;p=2075"},"modified":"2026-02-19T09:32:16","modified_gmt":"2026-02-19T08:32:16","slug":"was-kostet-ein-besuch-bis-den-hausarzt-arztlicher-notdienst","status":"publish","type":"faq","link":"https:\/\/hapmaastricht.nl\/de\/haeufig-gestellte-fragen\/was-kostet-ein-besuch-bis-den-hausarzt-arztlicher-notdienst\/","title":{"rendered":"Wie viel kostet ein Besuch beim Huisartsen \u00c4rztlicher Notdienst?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die aktuellen Tarife sind <a href=\"https:\/\/hapmaastricht.nl\/tarieven\">hier<\/a>&nbsp;aufgef\u00fchrt&nbsp;. Diese Tarife gelten abends, nachts und am Wochenende und werden gesetzlich von der niederl\u00e4ndischen Gesundheitsbeh\u00f6rde (NZa) festgelegt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die aktuellen Tarife sind hier aufgef\u00fchrt. Diese Tarife gelten abends, nachts und am Wochenende und werden von der niederl\u00e4ndischen Gesundheitsbeh\u00f6rde (NZa) gesetzlich festgelegt.<\/p>\n","protected":false},"menu_order":240,"template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"editor_notices":[],"footnotes":""},"question_type":[5771],"class_list":["post-2075","faq","type-faq","status-publish","hentry","question_type-kosten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wie viel kostet ein Besuch beim Huisartsen \u00c4rztlicher Notdienst? - Hausarzt-Notfallpraxis Maastricht<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hapmaastricht.nl\/de\/haeufig-gestellte-fragen\/was-kostet-ein-besuch-in-der-notaufnahme-des-hausarztes\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie viel kostet ein Besuch beim Huisartsen \u00c4rztlicher Notdienst? - Hausarzt-Notfallpraxis Maastricht\" \/>\n<meta property=\"og:description\" content=\"Die aktuellen Tarife sind hier aufgef\u00fchrt. Diese Tarife gelten abends, nachts und am Wochenende und werden von der niederl\u00e4ndischen Gesundheitsbeh\u00f6rde (NZa) gesetzlich festgelegt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hapmaastricht.nl\/de\/haeufig-gestellte-fragen\/was-kostet-ein-besuch-in-der-notaufnahme-des-hausarztes\/\" \/>\n<meta property=\"og:site_name\" content=\"Hausarzt-Notfallpraxis Maastricht\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-19T08:32:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hapmaastricht.nl\\\/de\\\/haeufig-gestellte-fragen\\\/was-kostet-ein-besuch-in-der-notaufnahme-des-hausarztes\\\/\",\"url\":\"https:\\\/\\\/hapmaastricht.nl\\\/de\\\/haeufig-gestellte-fragen\\\/was-kostet-ein-besuch-in-der-notaufnahme-des-hausarztes\\\/\",\"name\":\"Wie viel kostet ein Besuch beim Huisartsen \u00c4rztlicher Notdienst? - Hausarzt-Notfallpraxis Maastricht\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hapmaastricht.nl\\\/de\\\/#website\"},\"datePublished\":\"2023-05-02T11:36:06+00:00\",\"dateModified\":\"2026-02-19T08:32:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hapmaastricht.nl\\\/de\\\/haeufig-gestellte-fragen\\\/was-kostet-ein-besuch-in-der-notaufnahme-des-hausarztes\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hapmaastricht.nl\\\/de\\\/haeufig-gestellte-fragen\\\/was-kostet-ein-besuch-in-der-notaufnahme-des-hausarztes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hapmaastricht.nl\\\/de\\\/haeufig-gestellte-fragen\\\/was-kostet-ein-besuch-in-der-notaufnahme-des-hausarztes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hapmaastricht.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQS\",\"item\":\"https:\\\/\\\/hapmaastricht.nl\\\/de\\\/haeufig-gestellte-fragen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Was kostet ein Besuch bei der Hausarztnotrufstelle?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hapmaastricht.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/hapmaastricht.nl\\\/de\\\/\",\"name\":\"Hausarzt-Notfallpraxis Maastricht\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hapmaastricht.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie viel kostet ein Besuch beim Huisartsen \u00c4rztlicher Notdienst? - Hausarzt-Notfallpraxis Maastricht","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hapmaastricht.nl\/de\/haeufig-gestellte-fragen\/was-kostet-ein-besuch-in-der-notaufnahme-des-hausarztes\/","og_locale":"de_DE","og_type":"article","og_title":"Wie viel kostet ein Besuch beim Huisartsen \u00c4rztlicher Notdienst? - Hausarzt-Notfallpraxis Maastricht","og_description":"Die aktuellen Tarife sind hier aufgef\u00fchrt. Diese Tarife gelten abends, nachts und am Wochenende und werden von der niederl\u00e4ndischen Gesundheitsbeh\u00f6rde (NZa) gesetzlich festgelegt.","og_url":"https:\/\/hapmaastricht.nl\/de\/haeufig-gestellte-fragen\/was-kostet-ein-besuch-in-der-notaufnahme-des-hausarztes\/","og_site_name":"Hausarzt-Notfallpraxis Maastricht","article_modified_time":"2026-02-19T08:32:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hapmaastricht.nl\/de\/haeufig-gestellte-fragen\/was-kostet-ein-besuch-in-der-notaufnahme-des-hausarztes\/","url":"https:\/\/hapmaastricht.nl\/de\/haeufig-gestellte-fragen\/was-kostet-ein-besuch-in-der-notaufnahme-des-hausarztes\/","name":"Wie viel kostet ein Besuch beim Huisartsen \u00c4rztlicher Notdienst? - Hausarzt-Notfallpraxis Maastricht","isPartOf":{"@id":"https:\/\/hapmaastricht.nl\/de\/#website"},"datePublished":"2023-05-02T11:36:06+00:00","dateModified":"2026-02-19T08:32:16+00:00","breadcrumb":{"@id":"https:\/\/hapmaastricht.nl\/de\/haeufig-gestellte-fragen\/was-kostet-ein-besuch-in-der-notaufnahme-des-hausarztes\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hapmaastricht.nl\/de\/haeufig-gestellte-fragen\/was-kostet-ein-besuch-in-der-notaufnahme-des-hausarztes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hapmaastricht.nl\/de\/haeufig-gestellte-fragen\/was-kostet-ein-besuch-in-der-notaufnahme-des-hausarztes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hapmaastricht.nl\/de\/"},{"@type":"ListItem","position":2,"name":"FAQS","item":"https:\/\/hapmaastricht.nl\/de\/haeufig-gestellte-fragen\/"},{"@type":"ListItem","position":3,"name":"Was kostet ein Besuch bei der Hausarztnotrufstelle?"}]},{"@type":"WebSite","@id":"https:\/\/hapmaastricht.nl\/de\/#website","url":"https:\/\/hapmaastricht.nl\/de\/","name":"Hausarzt-Notfallpraxis Maastricht","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hapmaastricht.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/hapmaastricht.nl\/de\/wp-json\/wp\/v2\/faq\/2075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hapmaastricht.nl\/de\/wp-json\/wp\/v2\/faq"}],"about":[{"href":"https:\/\/hapmaastricht.nl\/de\/wp-json\/wp\/v2\/types\/faq"}],"version-history":[{"count":2,"href":"https:\/\/hapmaastricht.nl\/de\/wp-json\/wp\/v2\/faq\/2075\/revisions"}],"predecessor-version":[{"id":9290,"href":"https:\/\/hapmaastricht.nl\/de\/wp-json\/wp\/v2\/faq\/2075\/revisions\/9290"}],"wp:attachment":[{"href":"https:\/\/hapmaastricht.nl\/de\/wp-json\/wp\/v2\/media?parent=2075"}],"wp:term":[{"taxonomy":"question_type","embeddable":true,"href":"https:\/\/hapmaastricht.nl\/de\/wp-json\/wp\/v2\/question_type?post=2075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}