{"id":2073,"date":"2023-05-02T13:35:26","date_gmt":"2023-05-02T11:35:26","guid":{"rendered":"https:\/\/multisite.mindd.dev\/hap-maastricht\/?post_type=faq&#038;p=2073"},"modified":"2026-06-17T13:47:10","modified_gmt":"2026-06-17T11:47:10","slug":"plaintes-compliments","status":"publish","type":"faq","link":"https:\/\/hapmaastricht.nl\/fr\/questions-frequentes\/plaintes-compliments\/","title":{"rendered":"Plaintes \/ Compliments"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Compliments<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00cates-vous satisfait des soins fournis par notre service d\u2019urgence g\u00e9n\u00e9raliste ? Vous pouvez alors toujours nous le faire savoir via <a href=\"mailto:info@hapmaastricht.nl\" target=\"_blank\" rel=\"noreferrer noopener\">info@hapmaastricht.nl<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><br>Plaintes<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nous faisons tout notre possible pour vous offrir les meilleurs soins possibles.<br>Tu n\u2019es toujours pas satisfait ? Faites-le nous savoir via <a href=\"https:\/\/forms.zenya.work\/prndmmhrn9\/200\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>ce formulaire de r\u00e9clamation<\/strong><\/a>. <br>Un responsable des plaintes impartial et ind\u00e9pendant examinera alors votre plainte. <br>Il ou elle ne juge pas si votre plainte est justifi\u00e9e ou non.<br><br><strong>Veuillez noter :<\/strong> Nous avons besoin <a href=\"https:\/\/hapmaastricht.nl\/wp-content\/uploads\/sites\/30\/2026\/03\/AKKOORDVERKLARING-Inzage-medisch-dossier.docx\"><strong>d\u2019une D\u00e9claration de Secret Professionnel<\/strong><\/a> . Ce faisant, vous nous donnez la permission de consulter vos donn\u00e9es. Et en discuter avec les coll\u00e8gues avec qui vous avez eu des contacts. <br>Vous envoyez ce formulaire avec le formulaire de plainte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tu pr\u00e9f\u00e8res appeler d\u2019abord l\u2019agent des plaintes ? Prenez alors rendez-vous via le secr\u00e9tariat au 043-3874204.<br>Apr\u00e8s avoir appel\u00e9, l\u2019agent des plaintes vous demandera de remplir le formulaire de plainte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avez-vous des questions concernant le signalement de votre plainte ? Courrier \u00e0 <a href=\"mailto:info@hapmaastricht.nl\" target=\"_blank\" rel=\"noreferrer noopener\">info@hapmaastricht.nl<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ne parvenez-vous pas \u00e0 r\u00e9gler l\u2019affaire avec l\u2019agent des plaintes ? Ensuite, vous pouvez soumettre la plainte au Comit\u00e9 des Litiges des Soins G\u00e9n\u00e9ralistes. Pour plus d\u2019informations, voir : <a href=\"https:\/\/www.skge.nl\/patienten\" target=\"_blank\" rel=\"noreferrer noopener\">www.skge.nl\/patienten<\/a>.<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Responsable des plaintes des coordonn\u00e9es<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Stichting Huisartsenpost Maastricht &amp; Heuvelland, <br>Attente. Responsable des plaintes<br>R\u00e9ponse num\u00e9ro 126<br>6200 WC Maastricht<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plaintes Discutez de la plainte directement avec le m\u00e9decin ou l&#8217;employ\u00e9 du poste d&rsquo;urgence des m\u00e9decins g\u00e9n\u00e9ralistes. Cela ne fonctionne-t-il pas\u00a0? Vous pouvez ensuite soumettre la plainte \u00e0 un responsable des plaintes ind\u00e9pendant et impartial. Toutes les plaintes re\u00e7ues par le responsable des plaintes, par t\u00e9l\u00e9phone et par \u00e9crit, peuvent \u00eatre trait\u00e9es. Ce processus ne permet pas de d\u00e9terminer si votre plainte est justifi\u00e9e ou non. Coordonn\u00e9es du responsable des plaintes T\u00e9l\u00e9phone 043 -387 42 04 (du lundi au jeudi entre 10 h et 12 h) Par lettre Stichting Huisartsenpost Maastricht &amp; Heuvelland, \u00e0 l&rsquo;attention. Responsable des plaintes Num\u00e9ro de r\u00e9ponse 126 6200 WC Maastricht Mail info@hapmaastricht.nl Si le processus de m\u00e9diation avec le responsable des plaintes \u00e9choue, vous pouvez [&#8230;]<\/p>\n","protected":false},"menu_order":229,"template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"editor_notices":[],"footnotes":""},"question_type":[41],"class_list":["post-2073","faq","type-faq","status-publish","hentry","question_type-plaintes-compliments"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plainte ou compliment\u00a0? - Poste d&#039;urgence g\u00e9n\u00e9raliste Maastricht<\/title>\n<meta name=\"description\" content=\"Discutez de la plainte directement avec le m\u00e9decin ou l&#039;employ\u00e9 du poste d&#039;urgence du m\u00e9decin g\u00e9n\u00e9raliste. Cela ne fonctionne-t-il pas\u00a0? Faites rapport au responsable des plaintes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hapmaastricht.nl\/fr\/questions-frequentes\/plaintes-compliments\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plainte ou compliment\u00a0? - Poste d&#039;urgence g\u00e9n\u00e9raliste Maastricht\" \/>\n<meta property=\"og:description\" content=\"Discutez de la plainte directement avec le m\u00e9decin ou l&#039;employ\u00e9 du poste d&#039;urgence du m\u00e9decin g\u00e9n\u00e9raliste. Cela ne fonctionne-t-il pas\u00a0? Faites rapport au responsable des plaintes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hapmaastricht.nl\/fr\/questions-frequentes\/plaintes-compliments\/\" \/>\n<meta property=\"og:site_name\" content=\"Poste d&#039;urgence g\u00e9n\u00e9raliste Maastricht\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-17T11:47:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hapmaastricht.nl\\\/fr\\\/questions-frequentes\\\/plaintes-compliments\\\/\",\"url\":\"https:\\\/\\\/hapmaastricht.nl\\\/fr\\\/questions-frequentes\\\/plaintes-compliments\\\/\",\"name\":\"Plainte ou compliment\u00a0? - Poste d&#039;urgence g\u00e9n\u00e9raliste Maastricht\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hapmaastricht.nl\\\/fr\\\/#website\"},\"datePublished\":\"2023-05-02T11:35:26+00:00\",\"dateModified\":\"2026-06-17T11:47:10+00:00\",\"description\":\"Discutez de la plainte directement avec le m\u00e9decin ou l'employ\u00e9 du poste d'urgence du m\u00e9decin g\u00e9n\u00e9raliste. Cela ne fonctionne-t-il pas\u00a0? Faites rapport au responsable des plaintes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hapmaastricht.nl\\\/fr\\\/questions-frequentes\\\/plaintes-compliments\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hapmaastricht.nl\\\/fr\\\/questions-frequentes\\\/plaintes-compliments\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hapmaastricht.nl\\\/fr\\\/questions-frequentes\\\/plaintes-compliments\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hapmaastricht.nl\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQs\",\"item\":\"https:\\\/\\\/hapmaastricht.nl\\\/fr\\\/questions-frequentes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plaintes\\\/Compliments\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hapmaastricht.nl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/hapmaastricht.nl\\\/fr\\\/\",\"name\":\"Poste d&#039;urgence g\u00e9n\u00e9raliste Maastricht\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hapmaastricht.nl\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plainte ou compliment\u00a0? - Poste d&#039;urgence g\u00e9n\u00e9raliste Maastricht","description":"Discutez de la plainte directement avec le m\u00e9decin ou l'employ\u00e9 du poste d'urgence du m\u00e9decin g\u00e9n\u00e9raliste. Cela ne fonctionne-t-il pas\u00a0? Faites rapport au responsable des plaintes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hapmaastricht.nl\/fr\/questions-frequentes\/plaintes-compliments\/","og_locale":"fr_FR","og_type":"article","og_title":"Plainte ou compliment\u00a0? - Poste d&#039;urgence g\u00e9n\u00e9raliste Maastricht","og_description":"Discutez de la plainte directement avec le m\u00e9decin ou l'employ\u00e9 du poste d'urgence du m\u00e9decin g\u00e9n\u00e9raliste. Cela ne fonctionne-t-il pas\u00a0? Faites rapport au responsable des plaintes.","og_url":"https:\/\/hapmaastricht.nl\/fr\/questions-frequentes\/plaintes-compliments\/","og_site_name":"Poste d&#039;urgence g\u00e9n\u00e9raliste Maastricht","article_modified_time":"2026-06-17T11:47:10+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hapmaastricht.nl\/fr\/questions-frequentes\/plaintes-compliments\/","url":"https:\/\/hapmaastricht.nl\/fr\/questions-frequentes\/plaintes-compliments\/","name":"Plainte ou compliment\u00a0? - Poste d&#039;urgence g\u00e9n\u00e9raliste Maastricht","isPartOf":{"@id":"https:\/\/hapmaastricht.nl\/fr\/#website"},"datePublished":"2023-05-02T11:35:26+00:00","dateModified":"2026-06-17T11:47:10+00:00","description":"Discutez de la plainte directement avec le m\u00e9decin ou l'employ\u00e9 du poste d'urgence du m\u00e9decin g\u00e9n\u00e9raliste. Cela ne fonctionne-t-il pas\u00a0? Faites rapport au responsable des plaintes.","breadcrumb":{"@id":"https:\/\/hapmaastricht.nl\/fr\/questions-frequentes\/plaintes-compliments\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hapmaastricht.nl\/fr\/questions-frequentes\/plaintes-compliments\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hapmaastricht.nl\/fr\/questions-frequentes\/plaintes-compliments\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hapmaastricht.nl\/fr\/"},{"@type":"ListItem","position":2,"name":"FAQs","item":"https:\/\/hapmaastricht.nl\/fr\/questions-frequentes\/"},{"@type":"ListItem","position":3,"name":"Plaintes\/Compliments"}]},{"@type":"WebSite","@id":"https:\/\/hapmaastricht.nl\/fr\/#website","url":"https:\/\/hapmaastricht.nl\/fr\/","name":"Poste d&#039;urgence g\u00e9n\u00e9raliste Maastricht","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hapmaastricht.nl\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/hapmaastricht.nl\/fr\/wp-json\/wp\/v2\/faq\/2073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hapmaastricht.nl\/fr\/wp-json\/wp\/v2\/faq"}],"about":[{"href":"https:\/\/hapmaastricht.nl\/fr\/wp-json\/wp\/v2\/types\/faq"}],"version-history":[{"count":13,"href":"https:\/\/hapmaastricht.nl\/fr\/wp-json\/wp\/v2\/faq\/2073\/revisions"}],"predecessor-version":[{"id":9302,"href":"https:\/\/hapmaastricht.nl\/fr\/wp-json\/wp\/v2\/faq\/2073\/revisions\/9302"}],"wp:attachment":[{"href":"https:\/\/hapmaastricht.nl\/fr\/wp-json\/wp\/v2\/media?parent=2073"}],"wp:term":[{"taxonomy":"question_type","embeddable":true,"href":"https:\/\/hapmaastricht.nl\/fr\/wp-json\/wp\/v2\/question_type?post=2073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}